{"id":8136,"date":"2026-04-24T09:36:15","date_gmt":"2026-04-24T07:36:15","guid":{"rendered":"https:\/\/todocarritos.com\/acciaio-inossidabile"},"modified":"2026-04-28T10:09:02","modified_gmt":"2026-04-28T08:09:02","slug":"acciaio-inossidabile","status":"publish","type":"page","link":"https:\/\/todocarritos.com\/it\/acciaio-inossidabile","title":{"rendered":"Acciaio inossidabile"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"8136\" class=\"elementor elementor-8136 elementor-8099\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b3190de e-flex e-con-boxed e-con e-parent\" data-id=\"b3190de\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2a43322 elementor-widget elementor-widget-shortcode\" data-id=\"2a43322\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"mkl-configurator-inline is-shortcode configure-product configurador\"  data-product_id=\"7943\"  data-price=\"1\"  data-regular_price=\"1\"  data-is_on_sale=\"\"  data-settings=\"{&quot;convert_base_price&quot;:false}\"  data-loading=\"Caricamento del configuratore in corso...\"  data-force_form=\"1\"><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-8136","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/todocarritos.com\/it\/wp-json\/wp\/v2\/pages\/8136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/todocarritos.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/todocarritos.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/todocarritos.com\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/todocarritos.com\/it\/wp-json\/wp\/v2\/comments?post=8136"}],"version-history":[{"count":1,"href":"https:\/\/todocarritos.com\/it\/wp-json\/wp\/v2\/pages\/8136\/revisions"}],"predecessor-version":[{"id":8137,"href":"https:\/\/todocarritos.com\/it\/wp-json\/wp\/v2\/pages\/8136\/revisions\/8137"}],"wp:attachment":[{"href":"https:\/\/todocarritos.com\/it\/wp-json\/wp\/v2\/media?parent=8136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}